{"id":1169,"date":"2023-06-12T16:23:51","date_gmt":"2023-06-12T16:23:51","guid":{"rendered":"https:\/\/galeriasopra.pl\/?p=1169"},"modified":"2023-06-19T22:13:52","modified_gmt":"2023-06-19T22:13:52","slug":"jan-bonawentura-ostrowski","status":"publish","type":"post","link":"https:\/\/galeriasopra.com\/en\/jan-bonawentura-ostrowski\/","title":{"rendered":"Jan Bonawentura Ostrowski"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1169\" class=\"elementor elementor-1169\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbb24ad elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no exad-sticky-section-no\" data-id=\"bbb24ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ac42d4 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0ac42d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c544314 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"c544314\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16baa60 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no exad-sticky-section-no\" data-id=\"16baa60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-583b544 exad-glass-effect-no exad-sticky-section-no\" data-id=\"583b544\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c72366b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"c72366b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Jan Bonawentura Ostrowski<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d02a930 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"d02a930\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf9b20 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"4bf9b20\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>He was born in Cz\u0119stochowa, but he has been connected with Warsaw all his life. Here he graduated from the sculpture department at the Academy of Fine Arts (diploma with Prof. Tadeusz \u0141odziana). He also studied painting at the Academia di Belle Arte \u201cBrera\u201d (diploma in the studio of Prof. Giorgio de Giorgia). He practices all the fine arts - from painting through graphics to sculpture. Numerous exhibitions in Poland and abroad: Milan (1973, 1974), Helsinki, Copenhagen (1979), Warsaw (1979), Paris (1975, 1980, 1981), Saint Tropez (1980), Vancouver - group exhibition (1983), Bonn (1986, 1987, 1988), Warsaw (1991, 1992, 1993, 1999, 2000, 2001). He started painting in the seventies. He debuted with a large solo exhibition at the 'ART' Gallery in Warsaw. Since then, he regularly exhibits his paintings in Poland and abroad. In a technical world full of violence, people miss the world of fairy tales like never before. Bonaventure's painting depicts this world. In his paintings there is a mood full of peace and harmony. The figures suspended in the sky, unreal, are full of inner warmth and serenity. This strange and fantastic world is presented in the colors of yellow and red, which further warms the picture. The music of the cosmic spheres that surrounds it, the radiation of light and space complete this other dimension that we intuitively sense.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c9c7739 exad-glass-effect-no exad-sticky-section-no\" data-id=\"c9c7739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2de53e4 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2de53e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451.jpg\" class=\"attachment-large size-large wp-image-1172\" alt=\"Jan Bonawentura Ostrowski\" srcset=\"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451.jpg 300w, https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451-150x150.jpg 150w, https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451-12x12.jpg 12w, https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c94b9b elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no exad-sticky-section-no\" data-id=\"3c94b9b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0513b15 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0513b15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f49657 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"9f49657\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6605d13 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6605d13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Works available in the gallery<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf925e0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"cf925e0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee5189b elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no exad-sticky-section-no\" data-id=\"ee5189b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08f8618 exad-glass-effect-no exad-sticky-section-no\" data-id=\"08f8618\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c31e93 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"7c31e93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We currently do not have works by this artist in the gallery<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4947c44 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no exad-sticky-section-no\" data-id=\"4947c44\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e979e0 exad-glass-effect-no exad-sticky-section-no\" data-id=\"1e979e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05d340c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"05d340c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Odkryj magiczny \u015bwiat Bonawentury &#8211; artysty zwi\u0105zanego z Warszaw\u0105, kt\u00f3ry poprzez swoje malarstwo przenosi nas do krainy ba\u015bni i marze\u0144.<\/p>","protected":false},"author":4,"featured_media":1172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jan Bonawentura Ostrowski - galeriasopra.com<\/title>\n<meta name=\"description\" content=\"Bonawentura - Malarz ba\u015bniowego \u015bwiata. Odkryj wyj\u0105tkowe obrazy pe\u0142ne harmonii, spokoju i magii. Zapoznaj si\u0119 z pracami artysty zwi\u0105zanego z Warszaw\u0105.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/galeriasopra.com\/en\/jan-bonawentura-ostrowski\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jan Bonawentura Ostrowski - galeriasopra.com\" \/>\n<meta property=\"og:description\" content=\"Bonawentura - Malarz ba\u015bniowego \u015bwiata. Odkryj wyj\u0105tkowe obrazy pe\u0142ne harmonii, spokoju i magii. Zapoznaj si\u0119 z pracami artysty zwi\u0105zanego z Warszaw\u0105.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galeriasopra.com\/en\/jan-bonawentura-ostrowski\/\" \/>\n<meta property=\"og:site_name\" content=\"galeriasopra.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T16:23:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-19T22:13:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hello@galeriasopra.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"hello@galeriasopra.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/\"},\"author\":{\"name\":\"hello@galeriasopra.com\",\"@id\":\"https:\/\/galeriasopra.com\/#\/schema\/person\/55d564cd927c466052955c94e8fca0f2\"},\"headline\":\"Jan Bonawentura Ostrowski\",\"datePublished\":\"2023-06-12T16:23:51+00:00\",\"dateModified\":\"2023-06-19T22:13:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\/\/galeriasopra.com\/#organization\"},\"articleSection\":[\"Artysta\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/\",\"url\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/\",\"name\":\"Jan Bonawentura Ostrowski - galeriasopra.com\",\"isPartOf\":{\"@id\":\"https:\/\/galeriasopra.com\/#website\"},\"datePublished\":\"2023-06-12T16:23:51+00:00\",\"dateModified\":\"2023-06-19T22:13:52+00:00\",\"description\":\"Bonawentura - Malarz ba\u015bniowego \u015bwiata. Odkryj wyj\u0105tkowe obrazy pe\u0142ne harmonii, spokoju i magii. Zapoznaj si\u0119 z pracami artysty zwi\u0105zanego z Warszaw\u0105.\",\"breadcrumb\":{\"@id\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/galeriasopra.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jan Bonawentura Ostrowski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/galeriasopra.com\/#website\",\"url\":\"https:\/\/galeriasopra.com\/\",\"name\":\"galeriasopra.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/galeriasopra.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/galeriasopra.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/galeriasopra.com\/#organization\",\"name\":\"galeriasopra.com\",\"url\":\"https:\/\/galeriasopra.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/galeriasopra.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/03\/logo-for-qr-2-01-e1686765766760.png\",\"contentUrl\":\"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/03\/logo-for-qr-2-01-e1686765766760.png\",\"width\":256,\"height\":256,\"caption\":\"galeriasopra.com\"},\"image\":{\"@id\":\"https:\/\/galeriasopra.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/galeriasopra.com\/#\/schema\/person\/55d564cd927c466052955c94e8fca0f2\",\"name\":\"hello@galeriasopra.com\",\"url\":\"https:\/\/galeriasopra.com\/en\/author\/hellogaleriasopra-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jan Bonawentura Ostrowski - galeriasopra.com","description":"Bonawentura - Malarz ba\u015bniowego \u015bwiata. Odkryj wyj\u0105tkowe obrazy pe\u0142ne harmonii, spokoju i magii. Zapoznaj si\u0119 z pracami artysty zwi\u0105zanego z Warszaw\u0105.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/galeriasopra.com\/en\/jan-bonawentura-ostrowski\/","og_locale":"en_GB","og_type":"article","og_title":"Jan Bonawentura Ostrowski - galeriasopra.com","og_description":"Bonawentura - Malarz ba\u015bniowego \u015bwiata. Odkryj wyj\u0105tkowe obrazy pe\u0142ne harmonii, spokoju i magii. Zapoznaj si\u0119 z pracami artysty zwi\u0105zanego z Warszaw\u0105.","og_url":"https:\/\/galeriasopra.com\/en\/jan-bonawentura-ostrowski\/","og_site_name":"galeriasopra.com","article_published_time":"2023-06-12T16:23:51+00:00","article_modified_time":"2023-06-19T22:13:52+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/06\/1686587756451.jpg","type":"image\/jpeg"}],"author":"hello@galeriasopra.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"hello@galeriasopra.com","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/#article","isPartOf":{"@id":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/"},"author":{"name":"hello@galeriasopra.com","@id":"https:\/\/galeriasopra.com\/#\/schema\/person\/55d564cd927c466052955c94e8fca0f2"},"headline":"Jan Bonawentura Ostrowski","datePublished":"2023-06-12T16:23:51+00:00","dateModified":"2023-06-19T22:13:52+00:00","mainEntityOfPage":{"@id":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/"},"wordCount":213,"publisher":{"@id":"https:\/\/galeriasopra.com\/#organization"},"articleSection":["Artysta"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/","url":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/","name":"Jan Bonawentura Ostrowski - galeriasopra.com","isPartOf":{"@id":"https:\/\/galeriasopra.com\/#website"},"datePublished":"2023-06-12T16:23:51+00:00","dateModified":"2023-06-19T22:13:52+00:00","description":"Bonawentura - Malarz ba\u015bniowego \u015bwiata. Odkryj wyj\u0105tkowe obrazy pe\u0142ne harmonii, spokoju i magii. Zapoznaj si\u0119 z pracami artysty zwi\u0105zanego z Warszaw\u0105.","breadcrumb":{"@id":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/galeriasopra.com\/jan-bonawentura-ostrowski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/galeriasopra.com\/"},{"@type":"ListItem","position":2,"name":"Jan Bonawentura Ostrowski"}]},{"@type":"WebSite","@id":"https:\/\/galeriasopra.com\/#website","url":"https:\/\/galeriasopra.com\/","name":"galeriasopra.com","description":"","publisher":{"@id":"https:\/\/galeriasopra.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galeriasopra.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/galeriasopra.com\/#organization","name":"galeriasopra.com","url":"https:\/\/galeriasopra.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/galeriasopra.com\/#\/schema\/logo\/image\/","url":"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/03\/logo-for-qr-2-01-e1686765766760.png","contentUrl":"https:\/\/galeriasopra.com\/wp-content\/uploads\/2023\/03\/logo-for-qr-2-01-e1686765766760.png","width":256,"height":256,"caption":"galeriasopra.com"},"image":{"@id":"https:\/\/galeriasopra.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/galeriasopra.com\/#\/schema\/person\/55d564cd927c466052955c94e8fca0f2","name":"hello@galeriasopra.com","url":"https:\/\/galeriasopra.com\/en\/author\/hellogaleriasopra-com\/"}]}},"_links":{"self":[{"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/posts\/1169"}],"collection":[{"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/comments?post=1169"}],"version-history":[{"count":11,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/posts\/1169\/revisions"}],"predecessor-version":[{"id":1727,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/posts\/1169\/revisions\/1727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/media\/1172"}],"wp:attachment":[{"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/media?parent=1169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/categories?post=1169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/galeriasopra.com\/en\/wp-json\/wp\/v2\/tags?post=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}